{"id":6331,"date":"2019-03-11T22:12:25","date_gmt":"2019-03-11T22:12:25","guid":{"rendered":"https:\/\/kpattorney.com\/?p=6331"},"modified":"2025-10-28T13:44:22","modified_gmt":"2025-10-28T17:44:22","slug":"semi-truck-accident-liability-in-florida","status":"publish","type":"post","link":"https:\/\/kpattorney.com\/es\/blog\/semi-truck-accident-liability-in-florida\/","title":{"rendered":"Leyes de responsabilidad por accidentes de semirremolques en Florida"},"content":{"rendered":"<p>Si alguna vez ha estado involucrado o visto un accidente que involucra a un cami\u00f3n, sabe que el resultado puede ser dr\u00e1sticamente diferente al de los accidentes que involucran veh\u00edculos m\u00e1s peque\u00f1os. Si un sed\u00e1n, un SUV o una camioneta lo chocan por detr\u00e1s, es posible que su autom\u00f3vil solo sufra da\u00f1os menores. Sin embargo, si un cami\u00f3n con remolque lo golpea por detr\u00e1s, la gran diferencia de tama\u00f1o significa que est\u00e1 <a href=\"https:\/\/www.iihs.org\/research-areas\/fatality-statistics\/detail\/large-trucks\">m\u00e1s probabilidades de sufrir lesiones graves<\/a>.<\/p>\n<p>Los conductores de semirremolques deben cumplir requisitos m\u00e1s estrictos que los dem\u00e1s conductores. Estas normas adicionales pretenden reducir la probabilidad de accidentes catastr\u00f3ficos en las carreteras y autopistas del pa\u00eds. Algunos de estos requisitos tambi\u00e9n est\u00e1n pensados para facilitar la conducci\u00f3n de los camiones. <a href=\"https:\/\/kpattorney.com\/es\/personal-injury\/vehicle\/truck-accidents\/\">accidente de cami\u00f3n<\/a> a las v\u00edctimas para que reciban la indemnizaci\u00f3n que merecen en caso de que un camionero negligente no cumpla las normas y reglamentos pertinentes.<\/p>\n<h2><strong>Requisitos de seguro<\/strong><\/h2>\n<p>Todos los conductores de Florida deben tener al menos $10,000 en seguro de responsabilidad. Sin embargo, los conductores de camiones deben llevar mucho m\u00e1s que esto porque su veh\u00edculo es mucho m\u00e1s grande y pasan m\u00e1s tiempo en las carreteras que la mayor\u00eda de los conductores. La ley de Florida les exige llevar <a href=\"https:\/\/www.flhsmv.gov\/ddl\/FirmCorpEtc.pdf\">$50.000 a $750.000 en seguros<\/a>, dependiendo del peso del veh\u00edculo, aunque muchas empresas de transporte transportan mucho m\u00e1s que el m\u00ednimo para evitar ser demandadas.<\/p>\n<p>Los camiones que transportan materiales peligrosos (HAZMAT) est\u00e1n sujetos a requisitos de seguro a\u00fan m\u00e1s estrictos. Los conductores deben llevar al menos $5 millones en cobertura de responsabilidad por da\u00f1os personales y a la propiedad debido al peligro potencial que representan estos materiales.<\/p>\n<h2><strong>Pasos a seguir despu\u00e9s de un accidente de cami\u00f3n<\/strong><\/h2>\n<p>Despu\u00e9s de un accidente, probablemente se sentir\u00e1 confundido y conmocionado. A pesar de estos sentimientos, es importante <a href=\"http:\/\/www.legalinfo.com\/content\/truck-accidents\/what-should-you-do-if-you-are-involved-in-a-truck-accident.html\">siga algunos pasos clave<\/a> para asegurarse de que la persona o personas que causaron el accidente sean responsables y que usted reciba una compensaci\u00f3n justa por cualquier lesi\u00f3n que haya sufrido.<\/p>\n<h3><strong><em>Mant\u00e9ngase en escena<\/em><\/strong><\/h3>\n<p>Incluso si usted no caus\u00f3 el accidente, debe permanecer en la escena. Si alguien result\u00f3 herido en el accidente y usted no se detiene, puede enfrentar repercusiones civiles o incluso cargos penales.<\/p>\n<p>Tan pronto como sea posible, debe llamar al 911 para notificar a la polic\u00eda. Debe anotar tantos detalles como pueda, incluido que la colisi\u00f3n involucr\u00f3 a un cami\u00f3n. Esto les ayudar\u00e1 a determinar c\u00f3mo responder en la escena del accidente.<\/p>\n<p>Si alguien ha resultado gravemente herido, no intente moverlo por su cuenta. Esto podr\u00eda empeorar sus lesiones. Tampoco debe mover su veh\u00edculo hasta que la polic\u00eda se lo indique, ya que esto puede obstaculizar su investigaci\u00f3n.<\/p>\n<h3><strong><em>Documentar el accidente<\/em><\/strong><\/h3>\n<p>Si es posible, tome fotograf\u00edas de los veh\u00edculos da\u00f1ados y del lugar del accidente. Esto puede ayudar a los investigadores a determinar qu\u00e9 caus\u00f3 el accidente. Tambi\u00e9n debe anotar la informaci\u00f3n de contacto de todos los conductores involucrados, as\u00ed como los detalles del seguro y la licencia de conducir.<\/p>\n<p>Cuando llegue la polic\u00eda, coopere con ellos pero no comparta ning\u00fan detalle innecesario ni diga nada que pueda indicar que usted tiene la culpa.<\/p>\n<p>Debe notificar a su compa\u00f1\u00eda de seguros sobre el accidente, pero evite hablar con los ajustadores en el lugar a menos que sean de su aseguradora. No d\u00e9 una declaraci\u00f3n escrita ni firme nada sin consultar a un abogado de confianza.<\/p>\n<h3><strong><em>Busque tratamiento m\u00e9dico y asistencia legal<\/em><\/strong><\/h3>\n<p>Si usted est\u00e1 gravemente herido, es probable que sea trasladado al hospital para su evaluaci\u00f3n. Incluso si usted no tiene ninguna lesi\u00f3n aparente, se recomienda que se realice un examen m\u00e9dico despu\u00e9s de un accidente de cami\u00f3n para descartar cualquier <a href=\"https:\/\/kpattorney.com\/es\/personal-injury\/vehicle\/car-accidents\/injuries\/internal\/\">lesiones internas<\/a> u otros problemas que pueden no presentarse inmediatamente.<\/p>\n<p>En los d\u00edas posteriores al accidente, debe buscar asistencia legal de un abogado calificado que se especialice en accidentes de camiones. Ellos pueden guiarlo a trav\u00e9s del proceso de toma de decisiones y ayudarlo a obtener una compensaci\u00f3n por da\u00f1os.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>If you have ever been in or seen a crash involving a semi-truck, you know the outcome can be drastically different than accidents involving smaller vehicles.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":12,"featured_media":6332,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[213],"tags":[],"class_list":["post-6331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Understanding Liability in Florida Semi-Truck Accidents<\/title>\n<meta name=\"description\" content=\"Semi-truck accidents can cause devastating injuries. Learn how Florida attorneys help victims hold negligent parties accountable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kpattorney.com\/es\/blog\/semi-truck-accident-liability-in-florida\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Understanding Liability in Florida Semi-Truck Accidents\" \/>\n<meta property=\"og:description\" content=\"Semi-truck accidents can cause devastating injuries. Learn how Florida attorneys help victims hold negligent parties accountable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kpattorney.com\/es\/blog\/semi-truck-accident-liability-in-florida\/\" \/>\n<meta property=\"og:site_name\" content=\"Kanner &amp; Pintaluga\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kpattorney\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-11T22:12:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-28T17:44:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kpattorney.com\/wp-content\/uploads\/2019\/03\/Semi-Truck-Accidents-in-Florida-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Jimenez\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Jimenez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/blog\\\/semi-truck-accident-liability-in-florida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/blog\\\/semi-truck-accident-liability-in-florida\\\/\"},\"author\":{\"name\":\"Daniel Jimenez\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#\\\/schema\\\/person\\\/342243e4d3a17ee2161d4c9514431b64\"},\"headline\":\"Semi-Truck Accident Liability Laws in Florida\",\"datePublished\":\"2019-03-11T22:12:25+00:00\",\"dateModified\":\"2025-10-28T17:44:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/blog\\\/semi-truck-accident-liability-in-florida\\\/\"},\"wordCount\":608,\"publisher\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/blog\\\/semi-truck-accident-liability-in-florida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kpattorney.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Semi-Truck-Accidents-in-Florida-scaled.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/blog\\\/semi-truck-accident-liability-in-florida\\\/\",\"url\":\"https:\\\/\\\/kpattorney.com\\\/blog\\\/semi-truck-accident-liability-in-florida\\\/\",\"name\":\"Understanding Liability in Florida Semi-Truck Accidents\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/blog\\\/semi-truck-accident-liability-in-florida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/blog\\\/semi-truck-accident-liability-in-florida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kpattorney.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Semi-Truck-Accidents-in-Florida-scaled.jpg\",\"datePublished\":\"2019-03-11T22:12:25+00:00\",\"dateModified\":\"2025-10-28T17:44:22+00:00\",\"description\":\"Semi-truck accidents can cause devastating injuries. Learn how Florida attorneys help victims hold negligent parties accountable.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/blog\\\/semi-truck-accident-liability-in-florida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kpattorney.com\\\/blog\\\/semi-truck-accident-liability-in-florida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/blog\\\/semi-truck-accident-liability-in-florida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kpattorney.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Semi-Truck-Accidents-in-Florida-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/kpattorney.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Semi-Truck-Accidents-in-Florida-scaled.jpg\",\"width\":2048,\"height\":1536,\"caption\":\"Personal injury lawyers for semi accidents\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/blog\\\/semi-truck-accident-liability-in-florida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kpattorney.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Semi-Truck Accident Liability Laws in Florida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#website\",\"url\":\"https:\\\/\\\/kpattorney.com\\\/\",\"name\":\"Kanner &amp; Pintaluga\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kpattorney.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#organization\",\"name\":\"Kanner & Pintaluga\",\"url\":\"https:\\\/\\\/kpattorney.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kpattorney.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/newresizedkplogo.png\",\"contentUrl\":\"https:\\\/\\\/kpattorney.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/newresizedkplogo.png\",\"width\":450,\"height\":94,\"caption\":\"Kanner & Pintaluga\"},\"image\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kpattorney\",\"https:\\\/\\\/x.com\\\/kpattorney\",\"https:\\\/\\\/www.instagram.com\\\/kpattorney\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kpattorney\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#\\\/schema\\\/person\\\/342243e4d3a17ee2161d4c9514431b64\",\"name\":\"Daniel Jimenez\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entendiendo la Responsabilidad en Accidentes de Semirremolque en Florida","description":"Los accidentes de camiones pueden causar lesiones devastadoras. Aprenda c\u00f3mo los abogados de Florida ayudan a las v\u00edctimas a responsabilizar a las partes negligentes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kpattorney.com\/es\/blog\/semi-truck-accident-liability-in-florida\/","og_locale":"es_MX","og_type":"article","og_title":"Understanding Liability in Florida Semi-Truck Accidents","og_description":"Semi-truck accidents can cause devastating injuries. Learn how Florida attorneys help victims hold negligent parties accountable.","og_url":"https:\/\/kpattorney.com\/es\/blog\/semi-truck-accident-liability-in-florida\/","og_site_name":"Kanner &amp; Pintaluga","article_publisher":"https:\/\/www.facebook.com\/kpattorney","article_published_time":"2019-03-11T22:12:25+00:00","article_modified_time":"2025-10-28T17:44:22+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/kpattorney.com\/wp-content\/uploads\/2019\/03\/Semi-Truck-Accidents-in-Florida-scaled.jpg","type":"image\/jpeg"}],"author":"Daniel Jimenez","twitter_misc":{"Escrito por":"Daniel Jimenez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kpattorney.com\/blog\/semi-truck-accident-liability-in-florida\/#article","isPartOf":{"@id":"https:\/\/kpattorney.com\/blog\/semi-truck-accident-liability-in-florida\/"},"author":{"name":"Daniel Jimenez","@id":"https:\/\/kpattorney.com\/#\/schema\/person\/342243e4d3a17ee2161d4c9514431b64"},"headline":"Semi-Truck Accident Liability Laws in Florida","datePublished":"2019-03-11T22:12:25+00:00","dateModified":"2025-10-28T17:44:22+00:00","mainEntityOfPage":{"@id":"https:\/\/kpattorney.com\/blog\/semi-truck-accident-liability-in-florida\/"},"wordCount":608,"publisher":{"@id":"https:\/\/kpattorney.com\/#organization"},"image":{"@id":"https:\/\/kpattorney.com\/blog\/semi-truck-accident-liability-in-florida\/#primaryimage"},"thumbnailUrl":"https:\/\/kpattorney.com\/wp-content\/uploads\/2019\/03\/Semi-Truck-Accidents-in-Florida-scaled.jpg","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kpattorney.com\/blog\/semi-truck-accident-liability-in-florida\/","url":"https:\/\/kpattorney.com\/blog\/semi-truck-accident-liability-in-florida\/","name":"Entendiendo la Responsabilidad en Accidentes de Semirremolque en Florida","isPartOf":{"@id":"https:\/\/kpattorney.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kpattorney.com\/blog\/semi-truck-accident-liability-in-florida\/#primaryimage"},"image":{"@id":"https:\/\/kpattorney.com\/blog\/semi-truck-accident-liability-in-florida\/#primaryimage"},"thumbnailUrl":"https:\/\/kpattorney.com\/wp-content\/uploads\/2019\/03\/Semi-Truck-Accidents-in-Florida-scaled.jpg","datePublished":"2019-03-11T22:12:25+00:00","dateModified":"2025-10-28T17:44:22+00:00","description":"Los accidentes de camiones pueden causar lesiones devastadoras. Aprenda c\u00f3mo los abogados de Florida ayudan a las v\u00edctimas a responsabilizar a las partes negligentes.","breadcrumb":{"@id":"https:\/\/kpattorney.com\/blog\/semi-truck-accident-liability-in-florida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kpattorney.com\/blog\/semi-truck-accident-liability-in-florida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kpattorney.com\/blog\/semi-truck-accident-liability-in-florida\/#primaryimage","url":"https:\/\/kpattorney.com\/wp-content\/uploads\/2019\/03\/Semi-Truck-Accidents-in-Florida-scaled.jpg","contentUrl":"https:\/\/kpattorney.com\/wp-content\/uploads\/2019\/03\/Semi-Truck-Accidents-in-Florida-scaled.jpg","width":2048,"height":1536,"caption":"Personal injury lawyers for semi accidents"},{"@type":"BreadcrumbList","@id":"https:\/\/kpattorney.com\/blog\/semi-truck-accident-liability-in-florida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kpattorney.com\/"},{"@type":"ListItem","position":2,"name":"Semi-Truck Accident Liability Laws in Florida"}]},{"@type":"WebSite","@id":"https:\/\/kpattorney.com\/#website","url":"https:\/\/kpattorney.com\/","name":"Kanner y Pintaluga","description":"","publisher":{"@id":"https:\/\/kpattorney.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kpattorney.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kpattorney.com\/#organization","name":"Kanner y Pintaluga","url":"https:\/\/kpattorney.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kpattorney.com\/#\/schema\/logo\/image\/","url":"https:\/\/kpattorney.com\/wp-content\/uploads\/2022\/07\/newresizedkplogo.png","contentUrl":"https:\/\/kpattorney.com\/wp-content\/uploads\/2022\/07\/newresizedkplogo.png","width":450,"height":94,"caption":"Kanner & Pintaluga"},"image":{"@id":"https:\/\/kpattorney.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kpattorney","https:\/\/x.com\/kpattorney","https:\/\/www.instagram.com\/kpattorney\/","https:\/\/www.linkedin.com\/company\/kpattorney\/"]},{"@type":"Person","@id":"https:\/\/kpattorney.com\/#\/schema\/person\/342243e4d3a17ee2161d4c9514431b64","name":"Daniel Jim\u00e9nez"}]}},"_links":{"self":[{"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/posts\/6331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/comments?post=6331"}],"version-history":[{"count":0,"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/posts\/6331\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/media\/6332"}],"wp:attachment":[{"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/media?parent=6331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/categories?post=6331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/tags?post=6331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}