{"id":10503,"date":"2021-12-08T16:49:15","date_gmt":"2021-12-08T16:49:15","guid":{"rendered":"https:\/\/kpattorney.com\/?p=10503"},"modified":"2025-03-18T11:57:00","modified_gmt":"2025-03-18T11:57:00","slug":"1-5m-settlement-reached-in-rear-end-collision-case","status":"publish","type":"post","link":"https:\/\/kpattorney.com\/es\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/","title":{"rendered":"Veredictos y acuerdos: Se alcanza un acuerdo $1.5M en un caso de colisi\u00f3n trasera"},"content":{"rendered":"<p><a href=\"https:\/\/kpattorney.com\/es\/offices\/florida\/orlando\/\">Orlando, Florida, Estados Unidos<\/a> - La Pr\u00e1ctica de Litigios por Lesiones Personales de la Firma recientemente resolvi\u00f3 un caso de choque trasero por $1,500,000.<\/p>\n<p>A principios de 2017, nuestro cliente fue embestido por detr\u00e1s por un se\u00f1or mayor que trabajaba como conductor para una gran empresa internacional. No hab\u00eda duda de que su empleado era el culpable de causar este accidente. Como resultado, nuestro cliente sufri\u00f3 lesiones graves en el tobillo izquierdo, la rodilla derecha, la cadera derecha, la mu\u00f1eca derecha y la zona lumbar. En un esfuerzo por aliviar su dolor, y adem\u00e1s de una cantidad significativa de tratamiento conservador, se someti\u00f3 a m\u00faltiples cirug\u00edas en varias partes del cuerpo, incluyendo su tobillo izquierdo, rodilla derecha, cadera derecha y mu\u00f1eca derecha.<\/p>\n<p>La empresa, sin embargo, neg\u00f3 que nuestro cliente sufriera lesiones graves como consecuencia de este accidente. La empresa neg\u00f3 adem\u00e1s que nuestro cliente necesitara cirug\u00eda o que fuera a necesitar tratamiento futuro para sus lesiones. En apoyo de esta afirmaci\u00f3n, la empresa contrat\u00f3 a dos cirujanos ortop\u00e9dicos con el fin de que emitieran dict\u00e1menes coherentes con su postura.<\/p>\n<p>Casi cinco a\u00f1os despu\u00e9s de este accidente, las partes asistieron a una mediaci\u00f3n ordenada por el tribunal en noviembre de 2021. En la mediaci\u00f3n, nuestro cliente fue representado por el abogado litigante de KP <a href=\"https:\/\/kpattorney.com\/es\/firm\/attorneys\/richard-rosenblum\/\">Richard Rosenblum<\/a>. A pesar de que la empresa neg\u00f3 la causalidad de las lesiones de nuestro cliente y la necesidad de tratamiento, tanto en el pasado como en el futuro, las partes pudieron llegar a un acuerdo en este caso por $1.500.000.<\/p>\n<p><strong>Consigue lo que mereces<\/strong><br \/>\nKanner &amp; Pintaluga es una firma demandante nacional agresiva, \u00e9tica y orientada a resultados comprometida a representar a v\u00edctimas de accidentes, lesiones graves y da\u00f1os a la propiedad. Con un equipo de casi 100 abogados, tenemos la experiencia y los conocimientos para lograr el resultado m\u00e1s favorable para nuestros clientes. Si podemos ayudarlo o si simplemente desea hablar con un abogado para obtener la ayuda que necesita, no dude en contactarnos. Nuestro equipo siempre est\u00e1 disponible para discutir sus derechos y asegurarse de que usted y su familia est\u00e9n protegidos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Orlando, FL &#8211; The Firm&#8217;s Personal Injury Litigation Practice recently settled a rear-end crash case for $1,500,000. In early 2017, our client was rear-ended by an<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":17,"featured_media":10505,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[348],"tags":[],"class_list":["post-10503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-verdicts-settlements"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Personal Injury Settlement: $1.5M | Orlando<\/title>\n<meta name=\"description\" content=\"Orlando personal injury law firm, Kanner &amp; Pintaluga, recently won a settlement for $1.5M. Learn more about the rear end accident &amp; case settlement, here!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kpattorney.com\/es\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Personal Injury Settlement: $1.5M | Orlando\" \/>\n<meta property=\"og:description\" content=\"Orlando personal injury law firm, Kanner &amp; Pintaluga, recently won a settlement for $1.5M. Learn more about the rear end accident &amp; case settlement, here!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kpattorney.com\/es\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/\" \/>\n<meta property=\"og:site_name\" content=\"Kanner &amp; Pintaluga\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kpattorney\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-08T16:49:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-18T11:57:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kpattorney.com\/wp-content\/uploads\/2021\/12\/rearend.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"724\" \/>\n\t<meta property=\"og:image:height\" content=\"482\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bemler\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"bemler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/verdicts-settlements\\\/1-5m-settlement-reached-in-rear-end-collision-case\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/verdicts-settlements\\\/1-5m-settlement-reached-in-rear-end-collision-case\\\/\"},\"author\":{\"name\":\"bemler\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#\\\/schema\\\/person\\\/b1a6f9084bf4aef454382a953fb68efd\"},\"headline\":\"Verdicts &#038; Settlements: $1.5M Settlement Reached in Rear-End Collision Case\",\"datePublished\":\"2021-12-08T16:49:15+00:00\",\"dateModified\":\"2025-03-18T11:57:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/verdicts-settlements\\\/1-5m-settlement-reached-in-rear-end-collision-case\\\/\"},\"wordCount\":330,\"publisher\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/verdicts-settlements\\\/1-5m-settlement-reached-in-rear-end-collision-case\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kpattorney.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/rearend.jpg\",\"articleSection\":[\"Verdicts &amp; Settlements\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/verdicts-settlements\\\/1-5m-settlement-reached-in-rear-end-collision-case\\\/\",\"url\":\"https:\\\/\\\/kpattorney.com\\\/verdicts-settlements\\\/1-5m-settlement-reached-in-rear-end-collision-case\\\/\",\"name\":\"Personal Injury Settlement: $1.5M | Orlando\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/verdicts-settlements\\\/1-5m-settlement-reached-in-rear-end-collision-case\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/verdicts-settlements\\\/1-5m-settlement-reached-in-rear-end-collision-case\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kpattorney.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/rearend.jpg\",\"datePublished\":\"2021-12-08T16:49:15+00:00\",\"dateModified\":\"2025-03-18T11:57:00+00:00\",\"description\":\"Orlando personal injury law firm, Kanner & Pintaluga, recently won a settlement for $1.5M. Learn more about the rear end accident & case settlement, here!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/verdicts-settlements\\\/1-5m-settlement-reached-in-rear-end-collision-case\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kpattorney.com\\\/verdicts-settlements\\\/1-5m-settlement-reached-in-rear-end-collision-case\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/verdicts-settlements\\\/1-5m-settlement-reached-in-rear-end-collision-case\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kpattorney.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/rearend.jpg\",\"contentUrl\":\"https:\\\/\\\/kpattorney.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/rearend.jpg\",\"width\":724,\"height\":482,\"caption\":\"July 7,2020, Cena, Latvia, damaged cars on the highway at the scene of an accident because of non-observance of distance\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/verdicts-settlements\\\/1-5m-settlement-reached-in-rear-end-collision-case\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kpattorney.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verdicts &#038; Settlements: $1.5M Settlement Reached in Rear-End Collision Case\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#website\",\"url\":\"https:\\\/\\\/kpattorney.com\\\/\",\"name\":\"Kanner &amp; Pintaluga\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kpattorney.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#organization\",\"name\":\"Kanner & Pintaluga\",\"url\":\"https:\\\/\\\/kpattorney.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kpattorney.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/newresizedkplogo.png\",\"contentUrl\":\"https:\\\/\\\/kpattorney.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/newresizedkplogo.png\",\"width\":450,\"height\":94,\"caption\":\"Kanner & Pintaluga\"},\"image\":{\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kpattorney\",\"https:\\\/\\\/x.com\\\/kpattorney\",\"https:\\\/\\\/www.instagram.com\\\/kpattorney\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kpattorney\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kpattorney.com\\\/#\\\/schema\\\/person\\\/b1a6f9084bf4aef454382a953fb68efd\",\"name\":\"bemler\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acuerdo por lesiones personales: $1.5M | Orlando","description":"Orlando lesiones personales bufete de abogados, Kanner y Pintaluga, recientemente gan\u00f3 un acuerdo para $1.5M. Obtenga m\u00e1s informaci\u00f3n sobre el accidente trasero y el acuerdo del caso, \u00a1aqu\u00ed!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kpattorney.com\/es\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/","og_locale":"es_MX","og_type":"article","og_title":"Personal Injury Settlement: $1.5M | Orlando","og_description":"Orlando personal injury law firm, Kanner & Pintaluga, recently won a settlement for $1.5M. Learn more about the rear end accident & case settlement, here!","og_url":"https:\/\/kpattorney.com\/es\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/","og_site_name":"Kanner &amp; Pintaluga","article_publisher":"https:\/\/www.facebook.com\/kpattorney","article_published_time":"2021-12-08T16:49:15+00:00","article_modified_time":"2025-03-18T11:57:00+00:00","og_image":[{"width":724,"height":482,"url":"https:\/\/kpattorney.com\/wp-content\/uploads\/2021\/12\/rearend.jpg","type":"image\/jpeg"}],"author":"bemler","twitter_misc":{"Escrito por":"bemler","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kpattorney.com\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/#article","isPartOf":{"@id":"https:\/\/kpattorney.com\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/"},"author":{"name":"bemler","@id":"https:\/\/kpattorney.com\/#\/schema\/person\/b1a6f9084bf4aef454382a953fb68efd"},"headline":"Verdicts &#038; Settlements: $1.5M Settlement Reached in Rear-End Collision Case","datePublished":"2021-12-08T16:49:15+00:00","dateModified":"2025-03-18T11:57:00+00:00","mainEntityOfPage":{"@id":"https:\/\/kpattorney.com\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/"},"wordCount":330,"publisher":{"@id":"https:\/\/kpattorney.com\/#organization"},"image":{"@id":"https:\/\/kpattorney.com\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/#primaryimage"},"thumbnailUrl":"https:\/\/kpattorney.com\/wp-content\/uploads\/2021\/12\/rearend.jpg","articleSection":["Verdicts &amp; Settlements"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kpattorney.com\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/","url":"https:\/\/kpattorney.com\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/","name":"Acuerdo por lesiones personales: $1.5M | Orlando","isPartOf":{"@id":"https:\/\/kpattorney.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kpattorney.com\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/#primaryimage"},"image":{"@id":"https:\/\/kpattorney.com\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/#primaryimage"},"thumbnailUrl":"https:\/\/kpattorney.com\/wp-content\/uploads\/2021\/12\/rearend.jpg","datePublished":"2021-12-08T16:49:15+00:00","dateModified":"2025-03-18T11:57:00+00:00","description":"Orlando lesiones personales bufete de abogados, Kanner y Pintaluga, recientemente gan\u00f3 un acuerdo para $1.5M. Obtenga m\u00e1s informaci\u00f3n sobre el accidente trasero y el acuerdo del caso, \u00a1aqu\u00ed!","breadcrumb":{"@id":"https:\/\/kpattorney.com\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kpattorney.com\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kpattorney.com\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/#primaryimage","url":"https:\/\/kpattorney.com\/wp-content\/uploads\/2021\/12\/rearend.jpg","contentUrl":"https:\/\/kpattorney.com\/wp-content\/uploads\/2021\/12\/rearend.jpg","width":724,"height":482,"caption":"July 7,2020, Cena, Latvia, damaged cars on the highway at the scene of an accident because of non-observance of distance"},{"@type":"BreadcrumbList","@id":"https:\/\/kpattorney.com\/verdicts-settlements\/1-5m-settlement-reached-in-rear-end-collision-case\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kpattorney.com\/"},{"@type":"ListItem","position":2,"name":"Verdicts &#038; Settlements: $1.5M Settlement Reached in Rear-End Collision Case"}]},{"@type":"WebSite","@id":"https:\/\/kpattorney.com\/#website","url":"https:\/\/kpattorney.com\/","name":"Kanner y Pintaluga","description":"","publisher":{"@id":"https:\/\/kpattorney.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kpattorney.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kpattorney.com\/#organization","name":"Kanner y Pintaluga","url":"https:\/\/kpattorney.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kpattorney.com\/#\/schema\/logo\/image\/","url":"https:\/\/kpattorney.com\/wp-content\/uploads\/2022\/07\/newresizedkplogo.png","contentUrl":"https:\/\/kpattorney.com\/wp-content\/uploads\/2022\/07\/newresizedkplogo.png","width":450,"height":94,"caption":"Kanner & Pintaluga"},"image":{"@id":"https:\/\/kpattorney.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kpattorney","https:\/\/x.com\/kpattorney","https:\/\/www.instagram.com\/kpattorney\/","https:\/\/www.linkedin.com\/company\/kpattorney\/"]},{"@type":"Person","@id":"https:\/\/kpattorney.com\/#\/schema\/person\/b1a6f9084bf4aef454382a953fb68efd","name":"bemler"}]}},"_links":{"self":[{"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/posts\/10503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/comments?post=10503"}],"version-history":[{"count":0,"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/posts\/10503\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/media\/10505"}],"wp:attachment":[{"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/media?parent=10503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/categories?post=10503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kpattorney.com\/es\/wp-json\/wp\/v2\/tags?post=10503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}